{"id":53067,"date":"2023-10-17T07:04:47","date_gmt":"2023-10-17T07:04:47","guid":{"rendered":"https:\/\/www.expondo.co.uk\/inspirations\/slushi-in-der-slush-maschine\/"},"modified":"2023-10-17T07:04:49","modified_gmt":"2023-10-17T07:04:49","slug":"slushi-in-der-slush-maschine","status":"publish","type":"post","link":"https:\/\/www.expondo.at\/inspirationen\/slushi-in-der-slush-maschine\/","title":{"rendered":"Wie bereitet man Slushies zu? Wir testen 3 Varianten!\u00a0"},"content":{"rendered":"\n<p><strong>Der Sommer ist die Zeit, in der wir st\u00e4ndig Erfrischung brauchen. Und was ist erfrischender als ein zuckers\u00fc\u00dfes Slush-Eis! Wenn Sie Lust auf einen k\u00fchlenden Slushie haben, lesen Sie unsere Schritt-f\u00fcr-Schritt-Anleitung in diesem Artikel. Wir zeigen Ihnen, welche Ger\u00e4te und Zutaten Sie brauchen.&nbsp;<\/strong>&nbsp;<\/p>\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" id=\"ub_table-of-contents-150cbbf3-16be-49fd-a251-0c62359870a7\" data-initiallyhideonmobile=\"false\"\n                    data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\"><div class=\"ub_table-of-contents-header\">\n                    <div class=\"ub_table-of-contents-title\"><\/div><\/div><\/div><div class=\"ub_table-of-contents-extra-container\"><div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \"><ul><li><a href=https:\/\/www.expondo.at\/inspirationen\/slushi-in-der-slush-maschine\/#0-wie-und-womit-macht-man-slush-eis->Wie und womit macht man Slush-Eis?&nbsp;<\/a><\/li><li><a href=https:\/\/www.expondo.at\/inspirationen\/slushi-in-der-slush-maschine\/#1-wie-lange-dauert-es-bis-das-getr%C3%A4nk-gefriert->Wie lange dauert es, bis das Getr\u00e4nk gefriert?&nbsp;<\/a><\/li><\/ul><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-wie-und-womit-macht-man-slush-eis-\">Wie und womit macht man Slush-Eis?&nbsp;<\/h2>\n\n\n\n<p>Unser Experte Micha\u0142 hat f\u00fcr Sie die <a href=\"https:\/\/www.expondo.at\/royal-catering-slush-maschine-3-x-12-liter-10011022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Slush-Maschine RCSL3\/12<\/a> von Royal Catering getestet. Mit ihr bereiten Sie das dickfl\u00fcssige Eisgetr\u00e4nk zu. Und so einfach stellen Sie Slush-Eis selbst her:\u00a0<\/p>\n\n\n\n<p>Bereiten Sie zun\u00e4chst die Grundmischung vor, aus der Sie Ihren Slushie zubereiten. (Sie sollte etwa 13 % Zucker enthalten.) Vermengen Sie dazu Zucker und Wasser gut miteinander (z.B. mit einem Mixer). Achten Sie darauf, nur Zutaten zu verwenden, die f\u00fcr die Herstellung von Speiseeis in Slush-Maschinen oder anderen Ger\u00e4ten geeignet sind.&nbsp;<\/p>\n\n\n\n<p>Sobald die Mischung vorbereitet ist, schlie\u00dfen Sie das Ger\u00e4t an die Stromversorgung an. Geben Sie nun die Fl\u00fcssigkeit in die Beh\u00e4lter. Gie\u00dfen Sie h\u00f6chstens bis zur markierten F\u00fcllmenge, aber nie \u00fcber die Markierung hinaus. Schlie\u00dflich dehnt sich die Mischung aus und nimmt an Volumen zu, sobald sie gefriert.&nbsp;<\/p>\n\n\n\n<p>Starten Sie die Maschine per Knopfdruck. Achten Sie darauf, dass Sie beim Start immer Fl\u00fcssigkeit im Gef\u00e4\u00df haben und das R\u00fchrwerk nicht trocken l\u00e4uft. Schalten Sie mit der mittleren Taste die K\u00fchlung f\u00fcr die Beh\u00e4lter ein, um den Slushie zu gefrieren. Beim Modell RCSL 3\/12 stellen Sie kalte Getr\u00e4nke mit dem Beh\u00e4lter her, der dem Bedienfeld am n\u00e4chsten liegt. Insgesamt sind aber alle Gef\u00e4\u00dfe zur Herstellung von Slush-Eis geeignet. Mit derselben Taste bestimmen Sie \u00fcbrigens auch die H\u00e4rte der Eismasse.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Sie wollen Ihre Getr\u00e4nke einige Stunden oder \u00fcber Nacht im Ger\u00e4t belassen? Dann stellen Sie die mittlere Taste auf Position II. So aktivieren Sie den Nachtmodus. Dieser h\u00e4lt die eiskalte Mischung fl\u00fcssig und schont gleichzeitig den Kompressor, sodass dieser seine lange Lebensdauer beh\u00e4lt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-wie-lange-dauert-es-bis-das-getr%C3%A4nk-gefriert-\">Wie lange dauert es, bis das Getr\u00e4nk gefriert?&nbsp;<\/h2>\n\n\n\n<p>Auf diese Frage gibt es keine eindeutige Antwort, da sie von vielen Faktoren abh\u00e4ngt. Die Zusammensetzung des Getr\u00e4nks, die Zutaten, die Anfangstemperatur und die Umgebungstemperatur spielen eine Rolle. Micha\u0142 hat f\u00fcr seinen Test folgende Mischung genutzt:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wasser mit einem Zuckergehalt von 13 % (wie in der Anleitung angegeben) im ersten Beh\u00e4lter,&nbsp;&nbsp;<\/li>\n\n\n\n<li>speziellen Sirup im zweiten Gef\u00e4\u00df und&nbsp;&nbsp;<\/li>\n\n\n\n<li>etwas f\u00fcr Erwachsene: eine klassische Margherita im dritten Beh\u00e4lter.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n              <div id=\"expondo-products-block_ba3357665d2a9fdec049b1ec1fca2c44\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-slush-maschine-2-x-2-l-digitales-bedienfeld-royal-catering-10012944\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10012944_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-slush-maschine-2-x-2-l-digitales-bedienfeld-royal-catering-10012944\">\n                        Slush-Maschine &#8211; 2 x 3 l &#8211; LED &#8211; digitales Bedienfeld &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-slush-maschine-2-x-10-l-led-10011634\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10011634_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-slush-maschine-2-x-10-l-led-10011634\">\n                        Slush-Maschine &#8211; 2 x 12 l &#8211; LED &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>1,149.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-slush-maschine-3-x-10-l-led-10011633\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10011633_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-slush-maschine-3-x-10-l-led-10011633\">\n                        Slush-Maschine &#8211; 3 x 12 l &#8211; LED &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>1,259.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/royal-catering-slush-maschine-2-x-6-liter-20-0c-mindesttemperatur-ice-cream-funktion-10011028\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10011028_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/royal-catering-slush-maschine-2-x-6-liter-20-0c-mindesttemperatur-ice-cream-funktion-10011028\">\n                        Slush-Maschine &#8211; 2 x 8 l &#8211; LED &#8211; Ice-Cream-Funktion &#8211; Royal Catering                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>1,099.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<p>Alle Beh\u00e4lter hatten eine \u00e4hnliche Temperatur. Das Ergebnis nach dem Einschalten und nach gemessener Zeit? Das Zuckerwasser erreichte nach einer Stunde die richtige Konsistenz, der Sirup f\u00fcr das Slush-Eis nach einer Stunde und zehn Minuten. Auf die Margherita musste er am l\u00e4ngsten warten: insgesamt etwa zwei Stunden. Aber die haben sich gelohnt!&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.expondo.pl\/inspirations\/wp-content\/uploads\/2021\/01\/michal_bio.png\" alt=\"\" class=\"wp-image-35324\" style=\"width:199px;height:199px\" srcset=\"https:\/\/www.expondo.at\/inspirationen\/wp-content\/uploads\/2021\/01\/michal_bio.png 500w, https:\/\/www.expondo.at\/inspirationen\/wp-content\/uploads\/2021\/01\/michal_bio-300x300.png 300w, https:\/\/www.expondo.at\/inspirationen\/wp-content\/uploads\/2021\/01\/michal_bio-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Micha\u0142 Or\u0142owski \u2013 K\u00fcchenchef renommierter Restaurants in Sydney und Warschau. Erfahrener und professioneller Gastwirt. Micha\u0142 begann seine gastronomische Reise bereits als Teenager. Im Sommer arbeitete er als Barkeeper und entdeckte dabei seine Liebe zur Gastronomie. Er sammelte \u00fcber Jahre zahlreiche Erfahrungen, vertiefte sein Wissen und perfektionierte seine Handwerkskunst. <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p style=\"font-size:16px\">Im Jahr 2007 reiste er nach Australien, wo er seine F\u00e4higkeiten vervollkommnete. Nach seiner R\u00fcckkehr leitete er als K\u00fcchenchef das Restaurant Lars, Lars &amp; Lars in Posen.&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"142\" height=\"88\" src=\"https:\/\/www.expondo.pl\/inspirations\/wp-content\/uploads\/2021\/01\/sign-orlowski.png\" alt=\"\" class=\"wp-image-35331\"\/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Sommer ist die Zeit, in der wir st\u00e4ndig Erfrischung brauchen. Und was ist erfrischender als&hellip;<\/p>\n","protected":false},"author":12,"featured_media":51357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","ub_ctt_via":"","rank_math_lock_modified_date":false,"_strive_post_notes":"","footnotes":""},"categories":[3106],"tags":[],"promotion":[],"class_list":["post-53067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomie-de-at"],"acf":[],"featured_image_src":"https:\/\/www.expondo.at\/inspirationen\/wp-content\/uploads\/2023\/06\/how-to-make-a-slushy-in-a-granite.jpg","author_info":{"display_name":"Alicja Wo\u017aniak","author_link":"https:\/\/www.expondo.at\/inspirationen\/author\/alicja-wozniak\/"},"reading_time":"","author_thumbnail":"https:\/\/secure.gravatar.com\/avatar\/d7a4899b4575c0730c4bfd7ac2448f88?s=96&d=mm&r=g","excerpt_full":"\n<p><strong>Der Sommer ist die Zeit, in der wir st\u00e4ndig Erfrischung brauchen. Und was ist erfrischender als ein zuckers\u00fc\u00dfes Slush-Eis! Wenn Sie Lust auf einen k\u00fchlenden Slushie haben, lesen Sie unsere Schritt-f\u00fcr-Schritt-Anleitung in diesem Artikel. Wir zeigen Ihnen, welche Ger\u00e4te und Zutaten Sie brauchen.&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-wie-und-womit-macht-man-slush-eis-\">Wie und womit macht man Slush-Eis?&nbsp;<\/h2>\n\n\n\n<p>Unser Experte Micha\u0142 hat f\u00fcr Sie die <a href=\"https:\/\/www.expondo.at\/royal-catering-slush-maschine-3-x-12-liter-10011022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Slush-Maschine RCSL3\/12<\/a> von Royal Catering getestet. Mit ihr bereiten Sie das dickfl\u00fcssige Eisgetr\u00e4nk zu. Und so einfach stellen Sie Slush-Eis selbst her:\u00a0<\/p>\n\n\n\n<p>Bereiten Sie zun\u00e4chst die Grundmischung vor, aus der Sie Ihren Slushie zubereiten. (Sie sollte etwa 13 % Zucker enthalten.) Vermengen Sie dazu Zucker und Wasser gut miteinander (z.B. mit einem Mixer). Achten Sie darauf, nur Zutaten zu verwenden, die f\u00fcr die Herstellung von Speiseeis in Slush-Maschinen oder anderen Ger\u00e4ten geeignet sind.&nbsp;<\/p>\n\n\n\n<p>Sobald die Mischung vorbereitet ist, schlie\u00dfen Sie das Ger\u00e4t an die Stromversorgung an. Geben Sie nun die Fl\u00fcssigkeit in die Beh\u00e4lter. Gie\u00dfen Sie h\u00f6chstens bis zur markierten F\u00fcllmenge, aber nie \u00fcber die Markierung hinaus. Schlie\u00dflich dehnt sich die Mischung aus und nimmt an Volumen zu, sobald sie gefriert.&nbsp;<\/p>\n\n\n\n<p>Starten Sie die Maschine per Knopfdruck. Achten Sie darauf, dass Sie beim Start immer Fl\u00fcssigkeit im Gef\u00e4\u00df haben und das R\u00fchrwerk nicht trocken l\u00e4uft. Schalten Sie mit der mittleren Taste die K\u00fchlung f\u00fcr die Beh\u00e4lter ein, um den Slushie zu gefrieren. Beim Modell RCSL 3\/12 stellen Sie kalte Getr\u00e4nke mit dem Beh\u00e4lter her, der dem Bedienfeld am n\u00e4chsten liegt. Insgesamt sind aber alle Gef\u00e4\u00dfe zur Herstellung von Slush-Eis geeignet. Mit derselben Taste bestimmen Sie \u00fcbrigens auch die H\u00e4rte der Eismasse.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Sie wollen Ihre Getr\u00e4nke einige Stunden oder \u00fcber Nacht im Ger\u00e4t belassen? Dann stellen Sie die mittlere Taste auf Position II. So aktivieren Sie den Nachtmodus. Dieser h\u00e4lt die eiskalte Mischung fl\u00fcssig und schont gleichzeitig den Kompressor, sodass dieser seine lange Lebensdauer beh\u00e4lt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-wie-lange-dauert-es-bis-das-getr%C3%A4nk-gefriert-\">Wie lange dauert es, bis das Getr\u00e4nk gefriert?&nbsp;<\/h2>\n\n\n\n<p>Auf diese Frage gibt es keine eindeutige Antwort, da sie von vielen Faktoren abh\u00e4ngt. Die Zusammensetzung des Getr\u00e4nks, die Zutaten, die Anfangstemperatur und die Umgebungstemperatur spielen eine Rolle. Micha\u0142 hat f\u00fcr seinen Test folgende Mischung genutzt:&nbsp;<\/p>\n\n\n\n<ul>\n\n\n\n<\/ul>\n\n\n\n\n\n<p>Alle Beh\u00e4lter hatten eine \u00e4hnliche Temperatur. Das Ergebnis nach dem Einschalten und nach gemessener Zeit? Das Zuckerwasser erreichte nach einer Stunde die richtige Konsistenz, der Sirup f\u00fcr das Slush-Eis nach einer Stunde und zehn Minuten. Auf die Margherita musste er am l\u00e4ngsten warten: insgesamt etwa zwei Stunden. Aber die haben sich gelohnt!&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns\">\n\n<\/div>\n","_links":{"self":[{"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/posts\/53067"}],"collection":[{"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/comments?post=53067"}],"version-history":[{"count":2,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/posts\/53067\/revisions"}],"predecessor-version":[{"id":53069,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/posts\/53067\/revisions\/53069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/media\/51357"}],"wp:attachment":[{"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/media?parent=53067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/categories?post=53067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/tags?post=53067"},{"taxonomy":"promotion","embeddable":true,"href":"https:\/\/www.expondo.at\/inspirationen\/wp-json\/wp\/v2\/promotion?post=53067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}